{"id":1,"name":"admin","url":"https:\/\/kerlen-taucher.de","description":"","link":"https:\/\/kerlen-taucher.de\/en\/author\/designcore\/","slug":"designcore","meta":{"feedzy_import_tour":false,"feedzy_hide_action_message":false},"_links":{"self":[{"href":"https:\/\/kerlen-taucher.de\/en\/wp-json\/wp\/v2\/users\/1"}],"collection":[{"href":"https:\/\/kerlen-taucher.de\/en\/wp-json\/wp\/v2\/users"}]}}